{"id":666,"date":"2023-12-19T17:15:15","date_gmt":"2023-12-19T08:15:15","guid":{"rendered":"https:\/\/igcore.thers.ac.jp\/en\/?page_id=666"},"modified":"2023-12-19T17:15:22","modified_gmt":"2023-12-19T08:15:22","slug":"uglip","status":"publish","type":"page","link":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/","title":{"rendered":"UGLIP"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"page\/uglip.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-666","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/igcore.thers.ac.jp\/en\/uglip\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/uglip\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/uglip\\\/#listItem\",\"name\":\"UGLIP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/uglip\\\/#listItem\",\"position\":2,\"name\":\"UGLIP\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/#organization\",\"name\":\"glycoscience research institute\",\"url\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/uglip\\\/#webpage\",\"url\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/uglip\\\/\",\"name\":\"UGLIP | glycoscience research institute\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/uglip\\\/#breadcrumblist\"},\"datePublished\":\"2023-12-19T17:15:15+09:00\",\"dateModified\":\"2023-12-19T17:15:22+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/\",\"name\":\"glycoscience research institute\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/igcore.thers.ac.jp\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"UGLIP | glycoscience research institute","description":"","canonical_url":"https:\/\/igcore.thers.ac.jp\/en\/uglip","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/igcore.thers.ac.jp\/en#listItem","position":1,"name":"Home","item":"https:\/\/igcore.thers.ac.jp\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/#listItem","name":"UGLIP"}},{"@type":"ListItem","@id":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/#listItem","position":2,"name":"UGLIP","previousItem":{"@type":"ListItem","@id":"https:\/\/igcore.thers.ac.jp\/en#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/igcore.thers.ac.jp\/en\/#organization","name":"glycoscience research institute","url":"https:\/\/igcore.thers.ac.jp\/en\/"},{"@type":"WebPage","@id":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/#webpage","url":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/","name":"UGLIP | glycoscience research institute","inLanguage":"ja","isPartOf":{"@id":"https:\/\/igcore.thers.ac.jp\/en\/#website"},"breadcrumb":{"@id":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/#breadcrumblist"},"datePublished":"2023-12-19T17:15:15+09:00","dateModified":"2023-12-19T17:15:22+09:00"},{"@type":"WebSite","@id":"https:\/\/igcore.thers.ac.jp\/en\/#website","url":"https:\/\/igcore.thers.ac.jp\/en\/","name":"glycoscience research institute","inLanguage":"ja","publisher":{"@id":"https:\/\/igcore.thers.ac.jp\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"666","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"created":"2023-12-19 08:15:03","updated":"2026-06-10 07:56:45","primary_term":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-6a2918bdaac24","slug":"web-page","graphName":"WebPage","label":"Web \u30da\u30fc\u30b8","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"limit_modified_date":false,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/igcore.thers.ac.jp\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUGLIP\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/igcore.thers.ac.jp\/en"},{"label":"UGLIP","link":"https:\/\/igcore.thers.ac.jp\/en\/uglip\/"}],"_links":{"self":[{"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/pages\/666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/comments?post=666"}],"version-history":[{"count":1,"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/pages\/666\/revisions"}],"predecessor-version":[{"id":667,"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/pages\/666\/revisions\/667"}],"wp:attachment":[{"href":"https:\/\/igcore.thers.ac.jp\/en\/wp-json\/wp\/v2\/media?parent=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}